{"id":2715,"date":"2019-12-10T01:30:43","date_gmt":"2019-12-10T00:30:43","guid":{"rendered":"http:\/\/annalubinski.com\/blog\/?p=2715"},"modified":"2019-12-10T01:30:43","modified_gmt":"2019-12-10T00:30:43","slug":"faire-ses-decorations-de-noel-tuto-diy","status":"publish","type":"post","link":"https:\/\/annalubinski.com\/blog\/faire-ses-decorations-de-noel-tuto-diy\/","title":{"rendered":"Faire ses d\u00e9corations de No\u00ebl &#8211; Tuto DIY"},"content":{"rendered":"\n<h3>Comment faire une boule de No\u00ebl en papier?<br><em>How to make a paper Christmas ball?<\/em> <\/h3>\n\n\n\n<p>Bonjour!<br><br>J&rsquo;esp\u00e8re que comme moi vous aimez d\u00e9cembre parce que c&rsquo;est le mois de No\u00ebl et que c&rsquo;est l&rsquo;occasion de faire plein de trucs no\u00ebliques. J&rsquo;avais envie de partager avec vous des choses que je trouve chouettes \u00e0 cette p\u00e9riode, dont des Do It Yourself de No\u00ebl.<br><br>J&rsquo;aime beaucoup les d\u00e9corations de No\u00ebl soit en verre peint, soit en papier. Je trouve que le fait main \u00e0 un charme fou et que suspendues sur le sapin, ces d\u00e9corations donnent un petit quelque chose en plus.<br><br>D&rsquo;o\u00f9 mon envie de vous donner envie de faire une boule de No\u00ebl personnalisable et personnelle que vous pourrez faire seul, en famille, avec vos amis ou avec des enfants.<br><br>Pour ceux qui ne sont pas anglophones, vous aurez besoin d&rsquo;une tasse, de ciseaux, de ficelle ou de ruban, de papier fin (papier journal, papier origami, etc.), de colle liquide, d&rsquo;un crayon et de mani\u00e8re facultative de peinture dor\u00e9e ou \u00e0 paillettes et d&rsquo;un pinceau<\/p>\n\n\n\n<p><em>Hello!<br><br>I hope that like me you like December because it&rsquo;s the month of Christmas and it&rsquo;s an opportunity to do lots of christmasy stuff. I wanted to share with you things that I find cool at this time, including Christmas&rsquo; DIYs.<br><br>I really like Christmas decorations in either painted glass or paper. I find that the handmade is crazy charming and hanging on the tree, these decorations give a little something more.<br><br>Hence my desire to make you want to make a customizable and personal Christmas ball that you can do alone, with family, with your friends or with children.<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"724\" height=\"1024\" src=\"http:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-724x1024.jpg\" alt=\"\" class=\"wp-image-2717\" srcset=\"https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-724x1024.jpg 724w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-212x300.jpg 212w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-450x637.jpg 450w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-353x500.jpg 353w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy.jpg 750w\" sizes=\"(max-width: 724px) 94vw, 724px\" \/><\/figure>\n\n\n\n<p><br>Le r\u00e9sultat final en papier journal, anse en ruban de r\u00e9cup\u00e9ration et peinture dor\u00e9e sur les arr\u00eates.<br><em>The final result made of newspaper, recycled ribbon and gold paint on the edges.<\/em><br><br><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" loading=\"lazy\" width=\"607\" height=\"1024\" src=\"http:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-photo-607x1024.jpg\" alt=\"\" class=\"wp-image-2716\" srcset=\"https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-photo-607x1024.jpg 607w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-photo-178x300.jpg 178w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-photo-450x759.jpg 450w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-photo-296x500.jpg 296w, https:\/\/annalubinski.com\/blog\/wp-content\/uploads\/2019\/12\/anna-lubinski-illustration-decoration-noel-diy-photo.jpg 750w\" sizes=\"(max-width: 607px) 94vw, 607px\" \/><\/figure>\n\n\n\n<p><br>J&rsquo;esp\u00e8re que ce DIY vous a plu! Si vous faites vos d\u00e9corations \u00e0 partir de ce tuto, envoyez moi le r\u00e9sultat en photo via les r\u00e9seaux sociaux!<br><em>I hope you enjoyed this DIY! If you make your decorations from this tutorial, send me the result in photo via social networks!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comment faire une boule de No\u00ebl en papier?How to make a paper Christmas ball? Bonjour! J&rsquo;esp\u00e8re que comme [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[25,54],"tags":[],"_links":{"self":[{"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/posts\/2715"}],"collection":[{"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/comments?post=2715"}],"version-history":[{"count":3,"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/posts\/2715\/revisions"}],"predecessor-version":[{"id":2721,"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/posts\/2715\/revisions\/2721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/media\/2718"}],"wp:attachment":[{"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/media?parent=2715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/categories?post=2715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/annalubinski.com\/blog\/wp-json\/wp\/v2\/tags?post=2715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}